{"id":6259,"date":"2013-12-21T15:44:37","date_gmt":"2013-12-21T22:44:37","guid":{"rendered":"http:\/\/rafaelfajardo.com\/portfolio\/?p=6259"},"modified":"2015-10-23T14:36:57","modified_gmt":"2015-10-23T20:36:57","slug":"code-drawing-39","status":"publish","type":"post","link":"https:\/\/rafaelfajardo.com\/portfolio\/code-drawing-39\/","title":{"rendered":"code drawing 39"},"content":{"rendered":"<p><a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.33.13.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5963\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.33.13.1024-512x384.png\" alt=\"2013-12-21-15.33.13.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.33.13.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.33.13.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.33.13.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.33.13.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.34.22.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5964\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.34.22.1024-512x384.png\" alt=\"2013-12-21-15.34.22.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.34.22.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.34.22.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.34.22.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.34.22.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.35.49.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5965\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.35.49.1024-512x384.png\" alt=\"2013-12-21-15.35.49.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.35.49.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.35.49.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.35.49.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.35.49.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.03.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5966\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.03.1024-512x384.png\" alt=\"2013-12-21-15.36.03.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.03.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.03.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.03.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.03.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.16.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5967\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.16.1024-512x384.png\" alt=\"2013-12-21-15.36.16.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.16.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.16.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.16.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.16.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.44.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5968\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.44.1024-512x384.png\" alt=\"2013-12-21-15.36.44.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.44.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.44.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.44.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.36.44.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.07.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5969\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.07.1024-512x384.png\" alt=\"2013-12-21-15.37.07.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.07.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.07.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.07.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.07.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.31.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5970\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.31.1024-512x384.png\" alt=\"2013-12-21-15.37.31.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.31.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.31.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.31.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.31.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.57.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5971\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.57.1024-512x384.png\" alt=\"2013-12-21-15.37.57.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.57.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.57.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.57.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.37.57.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.28.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5972\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.28.1024-512x384.png\" alt=\"2013-12-21-15.38.28.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.28.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.28.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.28.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.28.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.52.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5973\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.52.1024-512x384.png\" alt=\"2013-12-21-15.38.52.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.52.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.52.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.52.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.38.52.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.12.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5974\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.12.1024-512x384.png\" alt=\"2013-12-21-15.40.12.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.12.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.12.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.12.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.12.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.39.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5975\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.39.1024-512x384.png\" alt=\"2013-12-21-15.40.39.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.39.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.39.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.39.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.40.39.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.06.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5976\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.06.1024-512x384.png\" alt=\"2013-12-21-15.41.06.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.06.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.06.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.06.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.06.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.29.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5977\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.29.1024-512x384.png\" alt=\"2013-12-21-15.41.29.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.29.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.29.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.29.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.29.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.52.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5978\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.52.1024-512x384.png\" alt=\"2013-12-21-15.41.52.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.52.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.52.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.52.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.41.52.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.16.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5979\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.16.1024-512x384.png\" alt=\"2013-12-21-15.42.16.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.16.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.16.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.16.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.16.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.40.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5980\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.40.1024-512x384.png\" alt=\"2013-12-21-15.42.40.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.40.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.40.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.40.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.42.40.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a> <a href=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.43.04.1024.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5981\" src=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.43.04.1024-512x384.png\" alt=\"2013-12-21-15.43.04.1024\" width=\"512\" height=\"384\" srcset=\"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.43.04.1024-512x384.png 512w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.43.04.1024-256x192.png 256w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.43.04.1024.png 1024w, https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.43.04.1024-400x300.png 400w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/p>\n<p>code drawing 39, created on 2013-12-21. I left some vertical space between the horizontal lines to see if I could get more color interaction.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>code drawing 39, created on 2013-12-21. I left some vertical space between the horizontal lines to see if I could get more color interaction.<\/p>\n","protected":false},"author":1,"featured_media":5964,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[8,15],"class_list":["post-6259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-code-drawings","tag-code-drawings","tag-hopscotch"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/rafaelfajardo.com\/portfolio\/wp-content\/uploads\/2013-12-21-15.34.22.1024.png","jetpack_shortlink":"https:\/\/wp.me\/p6PWot-1CX","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/posts\/6259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/comments?post=6259"}],"version-history":[{"count":1,"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/posts\/6259\/revisions"}],"predecessor-version":[{"id":6260,"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/posts\/6259\/revisions\/6260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/media\/5964"}],"wp:attachment":[{"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/media?parent=6259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/categories?post=6259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rafaelfajardo.com\/portfolio\/wp-json\/wp\/v2\/tags?post=6259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}